{"id":235,"count":1,"description":"","link":"https:\/\/ra-stein-sonntag.de\/news\/tag\/arbeitsrecht-erstaunliche-rechtsirrtuemer-ich-brauche-unbedingt-einen-schriftlichen-arbeitsvertrag-fuer-ein-arbeitsverhaeltnis\/","name":"Arbeitsrecht: \u201eErstaunliche Rechtsirrt\u00fcmer!\u201c \u201eIch brauche unbedingt einen schriftlichen Arbeitsvertrag f\u00fcr ein Arbeitsverh\u00e4ltnis!\u201c","slug":"arbeitsrecht-erstaunliche-rechtsirrtuemer-ich-brauche-unbedingt-einen-schriftlichen-arbeitsvertrag-fuer-ein-arbeitsverhaeltnis","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/tags\/235"}],"collection":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts?tags=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}