{"id":991,"date":"2023-02-20T09:36:42","date_gmt":"2023-02-20T08:36:42","guid":{"rendered":"https:\/\/ra-stein-sonntag.de\/news\/?p=991"},"modified":"2023-02-20T09:36:42","modified_gmt":"2023-02-20T08:36:42","slug":"verspaetung-und-vorverlegung-von-flugzeiten-loesen-entschaedigungsansprueche-aus","status":"publish","type":"post","link":"https:\/\/ra-stein-sonntag.de\/news\/2023\/02\/20\/verspaetung-und-vorverlegung-von-flugzeiten-loesen-entschaedigungsansprueche-aus\/","title":{"rendered":"Versp\u00e4tung und Vorverlegung von Flugzeiten l\u00f6sen Entsch\u00e4digungsanspr\u00fcche aus!"},"content":{"rendered":"\n<p>Die Fluggastrechte werden durch den Europ\u00e4ische Gerichtshof (EuGH) gest\u00e4rkt und der EuGH erkennt auch dann eine Entsch\u00e4digung an, wenn der Flug um mehr als eine Stunde vorverlegt wird.<\/p>\n\n\n\n<p>Bisher hat eine versp\u00e4tete Ankunft am Zielflughafen einen Entsch\u00e4digungsanspruch ausl\u00f6sen k\u00f6nnen. Von einer Ankunftsversp\u00e4tung ist auszugehen, wenn der Flieger mehr als drei Stunden sp\u00e4ter als geplant am Zielort ankommt. Genaugenommen ist der Zeitpunkt entscheidend, zu dem mindestens eine Flugzeugt\u00fcr ge\u00f6ffnet wird und Flugg\u00e4ste aussteigen k\u00f6nnen. Diese gro\u00dfe Versp\u00e4tung wird mit einer Annullierung des Flugs gleichgesetzt. Die H\u00f6he der Entsch\u00e4digung h\u00e4ngt von der Flugstrecke ab. F\u00fcr die Kurzstrecke bis zu 1.500 km ist eine Entsch\u00e4digung von 250,00 \u20ac und f\u00fcr die Mittelstrecke von 1.500 km bis 3.500 km ist eine Entsch\u00e4digung von 400,00 \u20ac und f\u00fcr die Langstrecke ab 3.500 km ist eine Entsch\u00e4digung von 600,00 \u20ac zu zahlen.<\/p>\n\n\n\n<p>Bereits am 21.12.2021 hat der EuGH (Rechtssachen C-146\/20, C-188\/20, C-196\/20, C-270\/20, C-263\/20) entschieden, dass ein Flug als annulliert anzusehen sei, wenn das ausf\u00fchrende Luftfahrtunternehmen ihn um mehr als eine Stunde vorverlegt. Denn dadurch werde den Flugg\u00e4sten die M\u00f6glichkeit genommen, frei \u00fcber ihre Zeit zu verf\u00fcgen. Abh\u00e4ngig von der Flugstrecke l\u00f6se die erhebliche Vorverlegung eine Entsch\u00e4digung von bis zu 600,00 \u20ac aus. Allerdings ist eine Entsch\u00e4digung ausgeschlossen, wenn die Fluggesellschaft mindestens zwei Wochen vor dem Abflug die Vorverlegung bekannt gibt. Ferner k\u00f6nnen noch k\u00fcrzere Fristen gelten, wenn ein alternativer Flug zu \u00e4hnlichen Zeiten angeboten wird.<\/p>\n\n\n\n<p>Oliver Sonntag<br>Rechtsanwalt<br>Fachanwalt f\u00fcr Verkehrsrecht<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Fluggastrechte werden durch den Europ\u00e4ische Gerichtshof (EuGH) gest\u00e4rkt und der EuGH erkennt auch dann eine Entsch\u00e4digung an, wenn der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[11,19,160],"_links":{"self":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/991"}],"collection":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/comments?post=991"}],"version-history":[{"count":1,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/991\/revisions"}],"predecessor-version":[{"id":992,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/991\/revisions\/992"}],"wp:attachment":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/media?parent=991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/categories?post=991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/tags?post=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}