{"id":972,"date":"2023-01-31T20:09:08","date_gmt":"2023-01-31T19:09:08","guid":{"rendered":"https:\/\/ra-stein-sonntag.de\/news\/?p=972"},"modified":"2023-01-31T20:09:08","modified_gmt":"2023-01-31T19:09:08","slug":"arbeitsrecht-erstaunliche-rechtsirrtuemer-zeitarbeitsunternehmen-koennen-betriebsbedingt-kuendigen-wenn-der-kunde-keinen-arbeitskraeftebedarf-mehr-hat","status":"publish","type":"post","link":"https:\/\/ra-stein-sonntag.de\/news\/2023\/01\/31\/arbeitsrecht-erstaunliche-rechtsirrtuemer-zeitarbeitsunternehmen-koennen-betriebsbedingt-kuendigen-wenn-der-kunde-keinen-arbeitskraeftebedarf-mehr-hat\/","title":{"rendered":"Arbeitsrecht: Erstaunliche Rechtsirrt\u00fcmer!    \u201eZeitarbeitsunternehmen k\u00f6nnen betriebsbedingt k\u00fcndigen, wenn der Kunde keinen Arbeitskr\u00e4ftebedarf mehr hat!\u201c"},"content":{"rendered":"\n<p>Diese Aussage ist falsch!<\/p>\n\n\n\n<p>Das Leiharbeitsverh\u00e4ltnis erfolgt zwischen drei Vertragspartnern. Zwischen Zeitarbeitsunternehmen (Arbeitgeber) und Leiharbeitnehmer besteht ein ganz normales Arbeitsverh\u00e4ltnis. Zwischen Verleiher und Entleiher (Kunde) besteht ein Arbeitnehmer\u00fcberlassungsvertrag. Schlie\u00dflich kommt der Leiharbeitnehmer bei dem Kunden seiner Arbeitspflicht nach.<\/p>\n\n\n\n<p>Falls der Kunde den Auftrag mit dem Zeitarbeitsunternehmen beendet, besteht das Arbeitsverh\u00e4ltnis unver\u00e4ndert fort. Eine sofortige betriebsbedingte K\u00fcndigung ist unzul\u00e4ssig. Grunds\u00e4tzlich trifft immer und alleine den Arbeitgeber das Besch\u00e4ftigungsrisiko. Danach muss das Zeitarbeitsunternehmen f\u00fcr ausreichend viele Auftr\u00e4ge und Einsatzm\u00f6glichkeiten f\u00fcr die Arbeitnehmer sorgen. Selbst wenn Leiharbeitnehmer in Phasen zwischen zwei \u00dcberlassungsauftr\u00e4gen nicht eingesetzt werden k\u00f6nnen, muss das Zeitarbeitsunternehmen trotzdem die Arbeitsverg\u00fctung weiter zahlen.<\/p>\n\n\n\n<p>Erst dann, wenn das Zeitarbeitsunternehmen \u00fcber mehrere Wochen keine Kundenauftr\u00e4ge mehr akquirieren kann, kommt eine betriebsbedingte K\u00fcndigung in Betracht.<\/p>\n\n\n\n<p>Oliver Sonntag<\/p>\n\n\n\n<p>Rechtsanwalt<\/p>\n\n\n\n<p>Fachanwalt f\u00fcr Arbeitsrecht<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Aussage ist falsch! Das Leiharbeitsverh\u00e4ltnis erfolgt zwischen drei Vertragspartnern. Zwischen Zeitarbeitsunternehmen (Arbeitgeber) und Leiharbeitnehmer besteht ein ganz normales Arbeitsverh\u00e4ltnis. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[45,19,95,152],"_links":{"self":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/972"}],"collection":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/comments?post=972"}],"version-history":[{"count":1,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/972\/revisions"}],"predecessor-version":[{"id":973,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/972\/revisions\/973"}],"wp:attachment":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/media?parent=972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/categories?post=972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/tags?post=972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}