{"id":1350,"date":"2025-02-28T11:28:42","date_gmt":"2025-02-28T10:28:42","guid":{"rendered":"https:\/\/ra-stein-sonntag.de\/news\/?p=1350"},"modified":"2025-02-28T11:28:42","modified_gmt":"2025-02-28T10:28:42","slug":"so-urteilt-das-arbg-aachen-ordentliche-kuendigung-des-stabstellenleiters-einer-kreisverwaltung-wegen-verwicklung-in-die-sog-schleuseraffaere-wirksam","status":"publish","type":"post","link":"https:\/\/ra-stein-sonntag.de\/news\/2025\/02\/28\/so-urteilt-das-arbg-aachen-ordentliche-kuendigung-des-stabstellenleiters-einer-kreisverwaltung-wegen-verwicklung-in-die-sog-schleuseraffaere-wirksam\/","title":{"rendered":"So urteilt das ArbG Aachen: Ordentliche K\u00fcndigung des Stabstellenleiters einer Kreisverwaltung wegen Verwicklung in die sog. Schleuseraff\u00e4re wirksam"},"content":{"rendered":"\n<p>In einer nunmehr ver\u00f6ffentlichten Entscheidung des Arbeitsgerichts Aachen vom 10.12.2024 &#8211; 2 Ca 2092\/24 &#8211; hat die 2. Kammer entschieden, dass die au\u00dferordentliche fristlose K\u00fcndigung des Stabstellenleiters einer Kreisverwaltung wegen Nichteinhaltung der Zweiwochenfrist unwirksam, die ordentliche fristgerechte K\u00fcndigung jedoch wirksam ist.<\/p>\n\n\n\n<p>Der Kl\u00e4ger war seit 2018 zun\u00e4chst ehrenamtlich, ab 2020 auf Basis einer geringf\u00fcgigen Besch\u00e4ftigung bei dem beklagten Kreis als Leiter einer Stabstelle besch\u00e4ftigt. Am 17.04.2024 erfolgte eine Durchsuchung der R\u00e4umlichkeiten des Beklagten wegen des Verdachtes der Schleuserkriminalit\u00e4t gegen den Kl\u00e4ger. Am 17.04.2024 wurde der Kl\u00e4ger in Untersuchungshaft genommen und verblieb dort bis zum 08.07.2024. Mit Schreiben vom 19.06.2024 forderte der Beklagte den Kl\u00e4ger auf, sich zu den Vorw\u00fcrfen zu \u00e4u\u00dfern. Mit Schreiben vom 28.06.2024 k\u00fcndigte der Beklagte das Arbeitsverh\u00e4ltnis mit dem Kl\u00e4ger au\u00dferordentlich mit sofortiger Wirkung, hilfsweise ordentlich zum 30.09.2024.<\/p>\n\n\n\n<p>Die 2. Kammer des Arbeitsgerichts Aachen entschied, dass die f\u00fcr den Ausspruch einer au\u00dferordentlichen K\u00fcndigung gesetzlich vorgegebene Zweiwochenfrist nicht eingehalten worden ist. Der Kreis h\u00e4tte nach der Durchsuchung der R\u00e4umlichkeiten am 17.04.2024 weitere Ermittlungen aufnehmen m\u00fcssen, um die Zweiwochenfrist zu wahren. Der Beklagte wartete bis zum 19.06.2024.<\/p>\n\n\n\n<p>Die ordentliche fristgerechte K\u00fcndigung zum Ablauf des 30.09.2024 ist jedoch wirksam. Der Kl\u00e4ger hat durch das Zurverf\u00fcgungstellen seiner eigenen Wohnung f\u00fcr Scheinanmeldungen zur Erlangung von Aufenthaltserlaubnissen Dritter und die Annahme von Geldzahlungen hierf\u00fcr erheblich gegen seine arbeitsvertragliche Nebenpflicht der R\u00fccksichtnahme und Loyalit\u00e4t versto\u00dfen. Der Kl\u00e4ger stand aufgrund seiner herausgehobenen Stellung innerhalb der Kreisverwaltung im \u00f6ffentlichen Fokus, so dass ihn eine gesteigerte Loyalit\u00e4tsverpflichtung traf.<\/p>\n\n\n\n<p>Quelle: Arbeitsgerichts Aachen, Pressemitteilung vom 12.02.2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einer nunmehr ver\u00f6ffentlichten Entscheidung des Arbeitsgerichts Aachen vom 10.12.2024 &#8211; 2 Ca 2092\/24 &#8211; hat die 2. Kammer entschieden, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[92,5,45,19,95],"_links":{"self":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/1350"}],"collection":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/comments?post=1350"}],"version-history":[{"count":1,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/1350\/revisions"}],"predecessor-version":[{"id":1351,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/1350\/revisions\/1351"}],"wp:attachment":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/media?parent=1350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/categories?post=1350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/tags?post=1350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}