{"id":1177,"date":"2024-03-09T12:04:13","date_gmt":"2024-03-09T11:04:13","guid":{"rendered":"https:\/\/ra-stein-sonntag.de\/news\/?p=1177"},"modified":"2024-03-09T12:04:13","modified_gmt":"2024-03-09T11:04:13","slug":"arbeitsrecht-erstaunliche-rechtsirrtuemer-wenn-ich-im-urlaub-bin-darf-mich-der-arbeitgeber-nicht-kuendigen-2","status":"publish","type":"post","link":"https:\/\/ra-stein-sonntag.de\/news\/2024\/03\/09\/arbeitsrecht-erstaunliche-rechtsirrtuemer-wenn-ich-im-urlaub-bin-darf-mich-der-arbeitgeber-nicht-kuendigen-2\/","title":{"rendered":"Arbeitsrecht: Erstaunliche Rechtsirrt\u00fcmer!   \u201eWenn ich im Urlaub bin, darf mich der Arbeitgeber nicht k\u00fcndigen!\u201c"},"content":{"rendered":"\n<p>Diese Aussage ist nicht richtig. Der Urlaub bewirkt keine K\u00fcndigungssperre!<\/p>\n\n\n\n<p>Etwas anderes gilt auch dann nicht, wenn der Arbeitgeber von dem mehrw\u00f6chigen Auslandsurlaub wusste. Es ist also dringend anzuraten, dass im Falle einer l\u00e4ngeren Urlaubsabwesenheit regelm\u00e4\u00dfig der Briefkasten geleert und die Eingangspost \u00fcberpr\u00fcft wird. Denn nach Zugang der K\u00fcndigung wird die 3-w\u00f6chige Klagefrist nach \u00a7 4 K\u00fcndigungsschutzgesetz in Gang gesetzt.<\/p>\n\n\n\n<p>Nur in sehr engen Ausnahmef\u00e4llen ist die versp\u00e4tete K\u00fcndigungsschutzklage nachtr\u00e4glich mit einem speziellen Antrag noch m\u00f6glich.<\/p>\n\n\n\n<p>Oliver Sonntag<br>Rechtsanwalt<br>Fachanwalt f\u00fcr Arbeitsrecht<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Aussage ist nicht richtig. Der Urlaub bewirkt keine K\u00fcndigungssperre! Etwas anderes gilt auch dann nicht, wenn der Arbeitgeber von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/1177"}],"collection":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":1,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"predecessor-version":[{"id":1178,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/posts\/1177\/revisions\/1178"}],"wp:attachment":[{"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ra-stein-sonntag.de\/news\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}